{"text_format":"1","workbook":"xlsx","n_sheets":7,"sheets":["USER_GUIDE","INITIAL Assessment","DETAILED Evaluation","GLOSSARY","Assumptions and Thresholds","Demand and Cost Thresholds","Drop-Down Values"],"not_rendered":{"charts":0,"images":0,"macros":0,"external_links":0,"defined_names":5,"comments":0,"pivot_tables":0},"unopened":[],"bounds":{"document_bytes":16777216,"sheet_cells":100000,"rows_first":2000,"rows_last":500,"rows_between":2000,"halvings":0,"cell_chars":16384,"cell_head_chars":4096},"cells_cut":0,"cells_raw":0,"read":"whole","date_system":"1900"}

{"sheet":"USER_GUIDE","index":0,"n_rows":53,"n_cols":11,"rows_kept":53,"cut":false,"hidden":false,"merged":[[1,2,1,14],[21,2,24,10],[26,2,30,10],[40,10,41,10],[43,10,44,10],[4,2,7,10],[19,2,19,10],[10,2,10,10],[11,2,11,10],[12,2,12,10],[13,2,13,10],[14,2,14,10],[15,2,15,10],[52,2,61,10],[46,10,47,10],[40,2,47,8],[34,2,36,10],[49,2,49,10]]}
[]
[null,null,"About the Thresholds for Rapid Transit Mode Selection Tool"]
[]
[null,null,"Purpose"]
[null,null,"This Rapid Transit Alternative Assessment Tool provides assistance in evaluating the two key components of transit planning: (1) Selection of Transit Mode - Bus or Rail; and (2) Selection of the Operating Environment - Partially or fully segregated ROW. The ability of a transit service to fulfill the mobility needs of the population will ultimately depend on the quality of implementation and the operational system.\n"]
[]
[]
[]
[]
[null,null,"References"]
[null,null,"AS-H02 - HOW TO UNDERTAKE RAPID TRANSIT ALTERNATIVE ASSESSMENT"]
[null,null,"Agarwal, O. P., Gouthami Padam, Aroha Bahuguna, and Salvador Pena. 2014. Urban Transport Data Analysis Tool (UT-DAT) : user's manual (English). Energy Sector Management Assistance Program (ESMAP). Washington, DC: World Bank Group. http://documents.worldbank.org/curated/en/395261468147569317/Urban-Transport-Data-Analysis-Tool-UT-DAT-users-manual."]
[null,null,"n.d. Global BRT Data. Accessed 08 20, 2018. https://brtdata.org/."]
[null,null,"Moccia, Luigi, Duncan W Allen, and Eric C Bruun. 2018. \"A Technology Selection and Design Model of a Semi-Rapid Transit Line.\" Researchgate . "]
[null,null,"Reilly, Jack, and Herbert Levinson. 2011. Public Transport Capacity Analysis Procedures for Developing Cities. Washington DC: The International Bank for Reconstruction and Development / The World Bank."]
[null,null,"Vuchic, Vukan R. 1981. Urban Public Transportation Systems and Technology. Englewood Cliffs, NJ."]
[]
[null,null,"How to Use This Tool?"]
[]
[null,null,"STEP 1: Selecting the appropriate TAB for your needs"]
[]
[null,null,"(A) INITAL ASSESSMENT: This tab should be used by cities who are in the initial stages of transit planning and would like to carry out a quick assessment of the most appropriate transit technology and operating environment options for the city. It will require the city to provide generalized data that should be readily available and the objectives for transit planning."]
[]
[]
[]
[]
[null,null,"(B) DETAILED EVALUATION This tab should be used by cities who have defined one or more specific corridors and are looking for an assessment for a particular corridor for which there is a reliable estimate of demand from a travel demand model or other source. This tool provides a generalized evaluation based on best practices and criteria, and will not necessarily idetnify only a single mode as being most appropriate.  The city should also evaluate the alternatives with respect to context-specific goals and objectives."]
[]
[]
[]
[]
[]
[null,null,"STEP 2: ASSUMPTIONS and Thresholds"]
[]
[null,null,"The tool contains all the assumptions used in the tool. Most of the assumptions and thresholds are based on typical global transit standards and best practices or acceptable thresholds where essential. In some cases, historic evidence from low and middle income countries is used to define thresholds."]
[]
[]
[]
[null,null,"STEP 3: DATA Inputs and RESULTS"]
[]
[null,null,"Within each TAB, at the very top you will find a reference to the data needs, minimum quality requirements and possible sources for each data item. \nWhen you have the required data ready, you can fill in the data in the yellow shaded input cells, or select the inputs from the drop-down menu  in the orange shaded box. The grey boxes include calculations and should not be edited.\nAs soon as the data inputs are entered, the tool will automatically populate the results.",null,null,null,null,null,null,null,"Example Orange Input Selection Box"]
[]
[]
[null,null,null,null,null,null,null,null,null,null,"Example Yellow Input Entry Box"]
[]
[]
[null,null,null,null,null,null,null,null,null,null,"Example of Calculation"]
[]
[]
[null,null,"In addition to the above, the tool also provides a GLOSSARY of Terminologies and Description of Results."]
[]
[null,null,"How to Read the Results?"]
[null,null,"The results of the tool should be used not as direct recommendations but as preliminary guidance on appropriate mode(s) for the city, given prevailing conditions of population density and travel habits. The tool provides suggestions at higher and lower cases of Passenger Traffic Density (PTD), which allows for a more nuanced reading.  For instance, if the INITIAL ASSESSMENT tool suggests that rail is COMPETITIVE for the whole network where bus is FAVORABLE, it may well be that part of the network would be better off as rail. Mixed results could be interpreted in some instances to indicate a mixed-mode solution warranting at least DETAILED consideration by corridor. If PTD is known by segment/corridor, the DETAILED EVALUATION tool could be used to explore the particular segment that will work better as rail.  In effect, both tools together could be used to assign segments of a large notional network to either rapid (BRT A or Metro) or semirapid (BRT or LRT)."]

{"sheet":"INITIAL Assessment","index":1,"n_rows":59,"n_cols":8,"rows_kept":59,"cut":false,"hidden":false,"merged":[[1,1,1,7],[59,1,59,3],[33,1,33,7],[35,3,35,5],[35,6,35,7],[6,1,6,7],[7,1,7,7],[11,1,11,7],[18,5,18,7]]}
[]
[null,"Initial Mode Assessment Tool"]
[]
[null,"This tool is intended to help cities make an initial assessment among a set of modes that should be considered for the Alternative Analysis. The tool is designed to use data that are readily available to assess potential rapid transit modes that differ by technology and right-of-way. "]
[]
[]
[null,"DATA INPUTS"]
["A","DATA Inputs - Existing and Projected Demographic Profile"]
[1,"Enter the Local Transit Service Area",null,3000,"Sq. km"]
[2,"Enter the Local Transit Service Area Population",null,23305971,"Projected population may be used for horizon year, where available"]
[]
["B","DATA Inputs - Existing Transit Characteristics"]
[3,"Annual Local Public Transit Boardings in the Service Area",null,3088800000,"Number of unlinked trips made by local public transit modes annually. Multiply daily trip by 300"]
[4,"Mean Local Public Transport Trip Length",null,4,"km"]
[5,"Enter existing Maximum Peak Hour Person-Traffic Per Direction along any corridor",null,0,"Pass/peakhour/dir"]
[6,"Enter the Historical Daily Traffic Peak Hour Factor?*",null,0.06,"The ratio of PHPD passenger volume at the maxium load point for a typical route to its total daily boardngs in both directions "]
[]
[]
["C","DATA Estimations",null,"Higher Case","Lower Case "]
[7,"Average Current Population Density for the Local Transit Service Area",null,{"$f":"D10/D9","v":7768.6570000000002},{"$f":"D10/D9","v":7768.6570000000002},"Pop/Sq.km"]
[8,"Local Public Transport Annual Passenger-km Traveled",null,{"$f":"D13*D14","v":12355200000},{"$f":"D13*D14","v":12355200000},"Passenger-km"]
[9,"Post-Rapid passenger-km per square km",null,{"$f":"1.8*D21/D9","v":7413120},{"$f":"1.4*E21/D9","v":5765760},"Passenger-km/sqkm"]
[10,"Gross Post-Rapid passenger-km",null,{"$f":"$D$9*D22","v":22239360000},{"$f":"$D$9*E22","v":17297280000},"Passenger-km"]
[11,"Notional network route km per square km",null,{"$f":"0.6*EXP(1.735-0.28*LN($D$9))*EXP(-11.131+0.559*LN(D20)+0.327*LN(D22))","v":0.13967544651501212},{"$f":"1.275*EXP(1.735-0.28*LN($D$9))*EXP(-11.131+0.559*LN(E20)+0.327*LN(E22))","v":0.27339386283842115},"route-km/Sq.km"]
[12,"Notional network route kilometres",null,{"$f":"D24*$D$9","v":419.02633954503636},{"$f":"E24*$D$9","v":820.18158851526346},"Km"]
[13,"Notional Average Rapid Transit Trip Length ",null,{"$f":"2+0.165*($D$14^1.325)*(D25^0.286)","v":7.8233708895265481},{"$f":"2+0.165*($D$14^1.325)*(E25^0.286)","v":9.0565382065595994},"Km"]
[14,"Rapid transit share of gross Transit PKT",null,{"$f":"1/(1+EXP(5.235-0.5-0.43197*LN(D22)+0.0926*LN(D20)))","v":0.78052585922457562},{"$f":"1/(1+EXP(5.235+0.55-0.43197*LN(E22)+0.0926*LN(E20)))","v":0.52751546383439007},"Percentage",null," "]
[15,"Rapid transit passenger-km",null,{"$f":"D27*D23","v":17358395572.60466},{"$f":"E27*E23","v":9124582682.2733192},"Passenger-km"]
[16,"Notional Annual Rapid Transit Boardings",null,{"$f":"D28/D26","v":2218787248.8370738},{"$f":"E28/E26","v":1007513298.5873604}]
[17,"Indicative Passenger Traffic Density",null,{"$f":"D28/D25","v":41425547.595532484},{"$f":"E28/E25","v":11125076.214879593},"Passenger-km/route-km"]
[18,"Notional Number of Routes",null,{"$f":"MAX(1,0.85*EXP(-1.248+0.837*LN(D25)-0.156*LN(D9)))","v":10.959846812900757},{"$f":"MAX(1,0.85*EXP(-1.248+0.837*LN(E25)-0.156*LN(D9)))","v":19.227870121996496}]
[19,"Notional Peak Passenger Demand based on Peak Hour Factor",null,{"$f":"MAX($D15,($D$16*D29/(D31*300)))","v":40489.38432652827},{"$f":"MAX($D15,($D$16*E29/(E31*300)))","v":10479.718161137098},"Person/hour/dir"]
[]
[null,"INITIAL SET OF ROUTE AND MODE RECOMMENDATIONS"]
[]
[1,"Mode Alternatives",null,"Bus",null,null,"Rail"]
[2,"Mode-Service Type",null,"BRT Rapid","BRT Semi-Rapid 1","BRT Semi-Rapid 2","LRT Semi-Rapid","Metro/ Rail Rapid Transit"]
[3,"HIGHER CASE: Is the Mode Favorable for Higher Notional Peak Passenger Demands?",null,{"$f":"VLOOKUP($D$32/'Assumptions and Thresholds'!$G$16,'Drop-Down Values'!$K$11:$L$15,2)","v":"OVER CAPACITY"},{"$f":"VLOOKUP($D$32/'Assumptions and Thresholds'!$G$17,'Drop-Down Values'!$K$11:$L$15,2)","v":"OVER CAPACITY"},{"$f":"VLOOKUP($D$32/'Assumptions and Thresholds'!$G$18,'Drop-Down Values'!$K$11:$L$15,2)","v":"OVER CAPACITY"},{"$f":"VLOOKUP($D$32/'Assumptions and Thresholds'!$G$19,'Drop-Down Values'!$K$11:$L$15,2)","v":"OVER CAPACITY"},{"$f":"VLOOKUP($D$32/'Assumptions and Thresholds'!$G$20,'Drop-Down Values'!$K$11:$L$15,2)","v":"FAVORABLE"}]
[4,"HIGHER CASE: Is the Mode Cost Efficient at Higher Passenger Traffic Density?",null,{"$f":"IF($D$30/1000000>'Demand and Cost Thresholds'!$E25,'Drop-Down Values'!$L$6,VLOOKUP(D52/'Demand and Cost Thresholds'!$B24,'Drop-Down Values'!$K$2:$L$5,2))","v":"OVER CAPACITY"},{"$f":"IF($D$30/1000000>'Demand and Cost Thresholds'!$E26,'Drop-Down Values'!$L$6,VLOOKUP(E52/'Demand and Cost Thresholds'!$B24,'Drop-Down Values'!$K$2:$L$5,2))","v":"OVER CAPACITY"},{"$f":"IF($D$30/1000000>'Demand and Cost Thresholds'!$E26,'Drop-Down Values'!$L$6,VLOOKUP(F52/'Demand and Cost Thresholds'!$B24,'Drop-Down Values'!$K$2:$L$5,2))","v":"OVER CAPACITY"},{"$f":"IF($D$30/1000000>'Demand and Cost Thresholds'!$E27,'Drop-Down Values'!$L$6,VLOOKUP(G52/'Demand and Cost Thresholds'!$B24,'Drop-Down Values'!$K$2:$L$5,2))","v":"OVER CAPACITY"},{"$f":"IF($D$30/1000000>'Demand and Cost Thresholds'!$E28,'Drop-Down Values'!$L$6,VLOOKUP(H52/'Demand and Cost Thresholds'!$B24,'Drop-Down Values'!$K$2:$L$5,2))","v":"FAVORABLE"}]
[5,"LOWER CASE: Is the Mode Favorable for Lower Notional Peak Passenger Demands?",null,{"$f":"VLOOKUP($E$32/'Assumptions and Thresholds'!$G$16,'Drop-Down Values'!$K$11:$L$15,2)","v":"FAVORABLE"},{"$f":"VLOOKUP($E$32/'Assumptions and Thresholds'!$G$17,'Drop-Down Values'!$K$11:$L$15,2)","v":"FAVORABLE"},{"$f":"VLOOKUP($E$32/'Assumptions and Thresholds'!$G$18,'Drop-Down Values'!$K$11:$L$15,2)","v":"OVER CAPACITY"},{"$f":"VLOOKUP($E$32/'Assumptions and Thresholds'!$G$19,'Drop-Down Values'!$K$11:$L$15,2)","v":"FAVORABLE"},{"$f":"VLOOKUP($E$32/'Assumptions and Thresholds'!$G$20,'Drop-Down Values'!$K$11:$L$15,2)","v":"MARGINAL"}]
[6,"LOWER CASE: Is the Mode Cost Efficient at Lower Passenger Traffic Density?",null,{"$f":"IF($E$30/1000000>'Demand and Cost Thresholds'!$E25,'Drop-Down Values'!$L$6,VLOOKUP(D53/'Demand and Cost Thresholds'!$C24,'Drop-Down Values'!$K$2:$L$5,2))","v":"FAVORABLE"},{"$f":"IF($E$30/1000000>'Demand and Cost Thresholds'!$E26,'Drop-Down Values'!$L$6,VLOOKUP(E53/'Demand and Cost Thresholds'!$C24,'Drop-Down Values'!$K$2:$L$5,2))","v":"FAVORABLE"},{"$f":"IF($E$30/1000000>'Demand and Cost Thresholds'!$E26,'Drop-Down Values'!$L$6,VLOOKUP(F53/'Demand and Cost Thresholds'!$C24,'Drop-Down Values'!$K$2:$L$5,2))","v":"FAVORABLE"},{"$f":"IF($E$30/1000000>'Demand and Cost Thresholds'!$E27,'Drop-Down Values'!$L$6,VLOOKUP(G53/'Demand and Cost Thresholds'!$C24,'Drop-Down Values'!$K$2:$L$5,2))","v":"COMPETITIVE"},{"$f":"IF($E$30/1000000>'Demand and Cost Thresholds'!$E28,'Drop-Down Values'!$L$6,VLOOKUP(H53/'Demand and Cost Thresholds'!$C24,'Drop-Down Values'!$K$2:$L$5,2))","v":"COMPETITIVE"}]
[7,"MODE CHARACTERISTICS"]
[null,"ROW Options",null,"Physically separated busway or segregated bus lanes with continuous passing lane.  Max vehicle length 24m","Dedicated at-grade lanes with passing lane at stations and 'spot' priority features.  Max vehicle length 24m","Dedicated at-grade BRT lane with general traffic turns allowed at signals.  Max vehicle length 18m","Dedicated tracks at grade.  Maximum train length 150m","Elevated double track, maximum train length "]
[null,"Vehicle Set",null,"Standard, articulated or double articulated buses on elevated busway with platform level boarding.","Standard, articulated or double articulated buses with platform level boarding","Standard or articulated buses with platform level boarding","Single-articulated low-floor vehicles in single- or multiple-unit trains","High platform cars operating in multiple-unit trains"]
[null,"Propulsion",null,"Combustion/Hybrid","Combustion/Hybrid","Combustion/Hybrid","Electric","Electric"]
[null,"Typical Vehicle Capacity (fully loaded)",null,"80-220","80-150","80-150",215,"180-280"]
[null,"Typical Consist (Vehicles per Scheduled Unit)",null,"1","1","1","1-4","2-12"]
[null,"Maximum Effective Scheduled Unit Capacity ",null,172,172,116,657,1637]
[null,"Typical Headways (minutes)",null,"1-3","4-8","4-8","5-10","2-5"]
[null,"Typical Urban Stop Spacing (km)",null,"0.8-2km","0.6-1.5km","0.6-1.5km","0.6-1.5km","0.8-2km"]
[null,"Transfers Possible",null,"At Key Hubs","At Key Hubs","At Key Hubs","Yes","Yes"]
[null,"Indicative Total Annualized Cost per passenger-km at high PTD",null,{"$f":"'Assumptions and Thresholds'!M16","v":0.31800809498012605},{"$f":"'Assumptions and Thresholds'!M17","v":0.36159184695452085},{"$f":"'Assumptions and Thresholds'!M18","v":0.36159184695452085},{"$f":"'Assumptions and Thresholds'!M19","v":0.36929124263725205},{"$f":"'Assumptions and Thresholds'!M20","v":0.33749318972769782}]
[null,"Indicative Total Annualized Cost per passenger-km at low PTD",null,{"$f":"'Assumptions and Thresholds'!N16","v":0.4301316391665001},{"$f":"'Assumptions and Thresholds'!N17","v":0.43258717639424932},{"$f":"'Assumptions and Thresholds'!N18","v":0.43258717639424932},{"$f":"'Assumptions and Thresholds'!N19","v":0.47759396443888535},{"$f":"'Assumptions and Thresholds'!N20","v":0.47873727416156253}]
[null,"Typical Average Operating Speed (km/hr)",null,50,30,25,30,50]
[null,"Flexibility",null,"V. Low","Moderate","Moderate","Low","V. Low"]
[null,"Potential to Influence Development",null,"Excellent","Good","Fair","Good","Excellent"]
[]
[]
[null," "]

{"sheet":"DETAILED Evaluation","index":2,"n_rows":53,"n_cols":6,"rows_kept":53,"cut":false,"hidden":false,"merged":[[41,1,41,5],[1,1,1,5],[3,1,6,3],[30,1,30,5],[9,1,9,5],[10,1,10,5],[29,1,29,5],[14,4,14,5],[16,1,16,5]]}
[]
[null,"Corridor-specific Detailed Mode Evaluation Tool"]
[]
[null,"This tool is intended to help cities determine the most appropriate mode alternatives for a specific corridor. The tool is designed to use data that represent an informed opinion as to the extent of demand in the corridor with rapid transit in place. Please copy the tab for use for every different corridor. The final selection of Mode Alternative should be based on context-specific criteria, which can be more important than a small numerical difference in the Evaluation Score. "]
[]
[]
[]
[]
[]
[null,"DATA INPUTS"]
["A","DATA Inputs - Projected Transit Corridor Characteristics"]
[1,"What is the Length of the Planned Corridor?",null,22,"in Km"]
[2,"What are the Projected Annual Passenger Boardings for the planned Corridor in  the Available ROW?",null,{"$f":"40350*300","v":12105000},"boardings"]
[3,"What is the Projected Maximum Peak Hour Peak Direction Passenger Demand along the Corridor?",null,10000,"Persons/hour/dir"]
[4,"What is the type of ROW Availability?",null,"A","ROW Class A = fully grade-separated ROW, Class B = at-grade lane separation, Class C = mixed traffic. The estimated annual Passenger Boardings should be consistent with the operating characteristics of the ROW"]
[]
["B","Qualitative Assessment"]
[5,"Is there an electrified regional rail in the metro area?",null,"YES"]
[6,"Is there a local electrified rail (streetcar or tram) in the metro area?",null,"NO"]
[7,"Are articulated buses operated in the local service in the metro area?",null,"NO"]
[8,"Do exclusive bus lanes exist in the metro area?",null,"YES"]
[9,"Is there metro elsewhere in the country",null,"YES"]
[10,"Is there BRT semi-rapid elsewhere in the country",null,"YES"]
[11,"Is there BRT rapid elsewhere in the country",null,"YES"]
[]
["B","DATA Estimations - Projected Transit Corridor Characteristics",null,"Higher Case","Lower Case "]
[12,"Indicative Average Trip Length ",null,{"$f":"'Demand and Cost Thresholds'!B19","v":12.291271838354199},{"$f":"'Demand and Cost Thresholds'!C19","v":5.8611279981072002},"in Km"]
[13,"Indicative Passenger Traffic Density (in millions)",null,{"$f":"$D$13*D27/(1000000*$D$12)","v":6.7629929819671624},{"$f":"$D$13*E27/(1000000*$D$12)","v":3.2249524735039845},"Passenger-km/route-km"]
[]
[null,"MODE EVALUATION"]
[null,"Mode Characteristics"]
[null,null,null,"Mode Option 1","Mode Option 2","Mode Option 3"]
[1,"Select Mode Options",null,"BRT Rapid","BRT Semi-Rapid 1","BRT Semi-Rapid 2"]
[2,"Maximum Vehicle Capacity",null,{"$f":"VLOOKUP(D33,'Assumptions and Thresholds'!$A$16:$D$20,4)","v":172},{"$f":"VLOOKUP(E33,'Assumptions and Thresholds'!$A$16:$D$20,4)","v":172},{"$f":"VLOOKUP(F33,'Assumptions and Thresholds'!$A$16:$D$20,4)","v":116}]
[3,"Minimum Service Frequency per hour for projected PHPD ",null,{"$f":"$D14/D34","v":58.139534883720927},{"$f":"$D14/E34","v":58.139534883720927},{"$f":"$D14/F34","v":86.206896551724142}]
[4,"Maximum Service Frequency per hour at capacity",null,{"$f":"VLOOKUP('DETAILED Evaluation'!D33,'Assumptions and Thresholds'!$A$16:$F$20,6,FALSE)","v":190},{"$f":"VLOOKUP('DETAILED Evaluation'!E33,'Assumptions and Thresholds'!$A$16:$F$20,6,FALSE)","v":94},{"$f":"VLOOKUP('DETAILED Evaluation'!F33,'Assumptions and Thresholds'!$A$16:$F$20,6,FALSE)","v":71}]
[5,"Does Mode Option meet Capacity Needs?",null,{"$f":"IF(D35>D36,\"Over Capacity\",IF(D35<VLOOKUP('DETAILED Evaluation'!D33,'Assumptions and Thresholds'!$A$16:$E$20,5),\"Underutilized\",\"Within Capacity\"))","v":"Within Capacity"},{"$f":"IF(E35>E36,\"Over Capacity\",IF(E35<VLOOKUP('DETAILED Evaluation'!E33,'Assumptions and Thresholds'!$A$16:$E$20,5),\"Underutilized\",\"Within Capacity\"))","v":"Within Capacity"},{"$f":"IF(F35>F36,\"Over Capacity\",IF(F35<VLOOKUP('DETAILED Evaluation'!F33,'Assumptions and Thresholds'!$A$16:$E$20,5),\"Underutilized\",\"Within Capacity\"))","v":"Over Capacity"}]
[6,"Do Alignment Needs Meet ROW Availability?",null,{"$f":"IF($D15=\"C\",IF(VLOOKUP(TEXT(D33,0),'Assumptions and Thresholds'!$A16:$C20,3,FALSE)=\"C\",\"YES\",\"NO\"),IF(D15=\"B\",IF(OR((VLOOKUP(TEXT(D33,0),'Assumptions and Thresholds'!$A16:$C20,3,FALSE)=\"B\"),(VLOOKUP(TEXT(D33,0),'Assumptions and Thresholds'!$A16:$C20,3,FALSE)= \"C\")),\"YES\",\"NO\"), \"YES\"))","v":"YES"},{"$f":"IF($D15=\"C\",IF(VLOOKUP(TEXT(E33,0),'Assumptions and Thresholds'!$A16:$C20,3,FALSE)=\"C\",\"YES\",\"NO\"),IF(D15=\"B\",IF(OR((VLOOKUP(TEXT(E33,0),'Assumptions and Thresholds'!$A16:$C20,3,FALSE)=\"B\"),(VLOOKUP(TEXT(E33,0),'Assumptions and Thresholds'!$A16:$C20,3,FALSE)= \"C\")),\"YES\",\"NO\"), \"YES\"))","v":"YES"},{"$f":"IF($D15=\"C\",IF(VLOOKUP(TEXT(F33,0),'Assumptions and Thresholds'!$A16:$C20,3,FALSE)=\"C\",\"YES\",\"NO\"),IF(D15=\"B\",IF(OR((VLOOKUP(TEXT(F33,0),'Assumptions and Thresholds'!$A16:$C20,3,FALSE)=\"B\"),(VLOOKUP(TEXT(F33,0),'Assumptions and Thresholds'!$A16:$C20,3,FALSE)= \"C\")),\"YES\",\"NO\"), \"YES\"))","v":"YES"}]
[7,"Indicative Total Annualized Cost per passenger-km at high PTD",null,{"$f":"VLOOKUP(D33,'Demand and Cost Thresholds'!$A$34:$B$38,2,FALSE)","v":0.49895751029152635},{"$f":"VLOOKUP(E33,'Demand and Cost Thresholds'!$A$34:$B$38,2,FALSE)","v":0.46514587126014478},{"$f":"VLOOKUP(F33,'Demand and Cost Thresholds'!$A$34:$B$38,2,FALSE)","v":0.46514587126014478}]
[8,"Indicative Total Annualized Cost per passenger-km at low PTD",null,{"$f":"VLOOKUP(D33,'Demand and Cost Thresholds'!$A$34:$C$38,3,FALSE)","v":0.67988502695784403},{"$f":"VLOOKUP(E33,'Demand and Cost Thresholds'!$A$34:$C$38,3,FALSE)","v":0.54459763741421852},{"$f":"VLOOKUP(F33,'Demand and Cost Thresholds'!$A$34:$C$38,3,FALSE)","v":0.54459763741421852}]
[]
[null,"Detailed Mode Screening"]
[null,"(High = 3; Medium = 2; Low = 1; None = 0)"]
[1,"Provides Adequate Capacity (3)",null,{"$f":"IF(D$37=\"Over Capacity\",0,IF(D$37=\"Underutilized\",1,IF(AND(D$37=\"Within Capacity\",OR(VLOOKUP(D$33,'Demand and Cost Thresholds'!$A$34:$E$38,5)<'Demand and Cost Thresholds'!$C$31,VLOOKUP(D$33,'Demand and Cost Thresholds'!$A$34:$E$38,5)>'Demand and Cost Thresholds'!$B$31)),2,IF(AND(D$37=\"Within Capacity\",VLOOKUP(D$33,'Demand and Cost Thresholds'!$A$34:$E$38,5)<'Demand and Cost Thresholds'!$B$31,VLOOKUP(D$33,'Demand and Cost Thresholds'!$A$34:$E$38,5)>'Demand and Cost Thresholds'!$C$31),3))))","v":2},{"$f":"IF(E$37=\"Over Capacity\",0,IF(E$37=\"Underutilized\",1,IF(AND(E$37=\"Within Capacity\",OR(VLOOKUP(E$33,'Demand and Cost Thresholds'!$A$34:$E$38,5)<'Demand and Cost Thresholds'!$C$31,VLOOKUP(E$33,'Demand and Cost Thresholds'!$A$34:$E$38,5)>'Demand and Cost Thresholds'!$B$31)),2,IF(AND(E$37=\"Within Capacity\",VLOOKUP(E$33,'Demand and Cost Thresholds'!$A$34:$E$38,5)<'Demand and Cost Thresholds'!$B$31,VLOOKUP(E$33,'Demand and Cost Thresholds'!$A$34:$E$38,5)>'Demand and Cost Thresholds'!$C$31),3))))","v":2},{"$f":"IF(F$37=\"Over Capacity\",0,IF(F$37=\"Underutilized\",1,IF(AND(F$37=\"Within Capacity\",OR(VLOOKUP(F$33,'Demand and Cost Thresholds'!$A$34:$E$38,5)<'Demand and Cost Thresholds'!$C$31,VLOOKUP(F$33,'Demand and Cost Thresholds'!$A$34:$E$38,5)>'Demand and Cost Thresholds'!$B$31)),2,IF(AND(F$37=\"Within Capacity\",VLOOKUP(F$33,'Demand and Cost Thresholds'!$A$34:$E$38,5)<'Demand and Cost Thresholds'!$B$31,VLOOKUP(F$33,'Demand and Cost Thresholds'!$A$34:$E$38,5)>'Demand and Cost Thresholds'!$C$31),3))))","v":0}]
[2,"ROW Availability (Need vs. availability of dedicated corridors) (3)",null,{"$f":"IF(D38=\"YES\",3,0)","v":3},{"$f":"IF(E38=\"YES\",3,0)","v":3},3]
[3,"Potential to Integrate Pedestrian Needs (Such as safe crossings) (2)",null,{"$f":"IF(VLOOKUP(TEXT(D33,0),'Assumptions and Thresholds'!$A15:$K20,11,FALSE)=\"High\",0,IF(VLOOKUP(TEXT(D33,0),'Assumptions and Thresholds'!$A15:$K20,11,FALSE)=\"Moderate\",1,2))","v":0},{"$f":"IF(VLOOKUP(TEXT(E33,0),'Assumptions and Thresholds'!$A15:$K20,11,FALSE)=\"High\",0,IF(VLOOKUP(TEXT(E33,0),'Assumptions and Thresholds'!$A15:$K20,11,FALSE)=\"Moderate\",1,2))","v":2},{"$f":"IF(VLOOKUP(TEXT(F33,0),'Assumptions and Thresholds'!$A15:$K20,11,FALSE)=\"High\",0,IF(VLOOKUP(TEXT(F33,0),'Assumptions and Thresholds'!$A15:$K20,11,FALSE)=\"Moderate\",1,2))","v":2}]
[4,"Maintain livability (no noise and infrastructural clutter) (2)",null,{"$f":"IF(VLOOKUP(TEXT(D33,0),'Assumptions and Thresholds'!$A16:$L21,12,FALSE)=\"High\",0,IF(VLOOKUP(TEXT(D33,0),'Assumptions and Thresholds'!$A16:$L21,12,FALSE)=\"Moderate\",1,2))","v":1},{"$f":"IF(VLOOKUP(TEXT(E33,0),'Assumptions and Thresholds'!$A16:$L21,12,FALSE)=\"High\",0,IF(VLOOKUP(TEXT(E33,0),'Assumptions and Thresholds'!$A16:$L21,12,FALSE)=\"Moderate\",1,2))","v":2},{"$f":"IF(VLOOKUP(TEXT(F33,0),'Assumptions and Thresholds'!$A16:$L21,12,FALSE)=\"High\",0,IF(VLOOKUP(TEXT(F33,0),'Assumptions and Thresholds'!$A16:$L21,12,FALSE)=\"Moderate\",1,2))","v":2}]
[4,"Reliability Factor (Potential for Delay) (2)",null,{"$f":"IF(VLOOKUP(TEXT(D33,0),'Assumptions and Thresholds'!$A16:$J20,10,FALSE)=\"High\",2,IF(VLOOKUP(TEXT(D33,0),'Assumptions and Thresholds'!$A16:$J20,10,FALSE)=\"Moderate\",1,0))","v":2},{"$f":"IF(VLOOKUP(TEXT(E33,0),'Assumptions and Thresholds'!$A16:$J20,10,FALSE)=\"High\",2,IF(VLOOKUP(TEXT(E33,0),'Assumptions and Thresholds'!$A16:$J20,10,FALSE)=\"Moderate\",1,0))","v":1},{"$f":"IF(VLOOKUP(TEXT(F33,0),'Assumptions and Thresholds'!$A16:$J20,10,FALSE)=\"High\",2,IF(VLOOKUP(TEXT(F33,0),'Assumptions and Thresholds'!$A16:$J20,10,FALSE)=\"Moderate\",1,0))","v":1}]
[5,"High Estimate of TAC per PKT (High Cost = Low Score) (3)",null,{"$f":"VLOOKUP(D$33,'Demand and Cost Thresholds'!$A$40:$C$44,2,FALSE)","v":3},{"$f":"VLOOKUP(E$33,'Demand and Cost Thresholds'!$A$40:$C$44,2,FALSE)","v":3},{"$f":"VLOOKUP(F$33,'Demand and Cost Thresholds'!$A$40:$C$44,2,FALSE)","v":3}]
[6,"Low Estimate of TAC per PKT (High Cost = Low Score) (3)",null,{"$f":"VLOOKUP(D$33,'Demand and Cost Thresholds'!$A$40:$C$44,3,FALSE)","v":1},{"$f":"VLOOKUP(E$33,'Demand and Cost Thresholds'!$A$40:$C$44,3,FALSE)","v":3},{"$f":"VLOOKUP(F$33,'Demand and Cost Thresholds'!$A$40:$C$44,3,FALSE)","v":3}]
[7,"Ease of Implementation with respect to: Familiarity with Technology (2)",null,{"$f":"MIN(2,MAX(VLOOKUP(D33,'Drop-Down Values'!$Q$2:$S$6,2, FALSE),VLOOKUP('DETAILED Evaluation'!D33,'Drop-Down Values'!$Q$2:$S$6,3)))","v":1},{"$f":"MIN(2,MAX(VLOOKUP(E33,'Drop-Down Values'!$Q$2:$S$6,2, FALSE),VLOOKUP('DETAILED Evaluation'!E33,'Drop-Down Values'!$Q$2:$S$6,3)))","v":2},{"$f":"MIN(2,MAX(VLOOKUP(F33,'Drop-Down Values'!$Q$2:$S$6,2, FALSE),VLOOKUP('DETAILED Evaluation'!F33,'Drop-Down Values'!$Q$2:$S$6,3)))","v":2}]
[]
[null,"EVALUATION SCORE (Out of 20)",null,{"$f":"SUM(D44:D51)","v":13},{"$f":"SUM(E44:E51)","v":18},{"$f":"SUM(F44:F51)","v":16}]

{"sheet":"GLOSSARY","index":3,"n_rows":18,"n_cols":6,"rows_kept":18,"cut":false,"hidden":false,"merged":[]}
["TERMINOLOGIES","Acronyms","Description",null,"RESULTS","Description"]
["Capacity",null,"The maximum number of people that can be carried past a given location during a given time period under specified operating conditions, without unacceptable delay, hazard, or restriction, and with reasonable certainty",null,"FAVORABLE","Likely to be a good choice for the input conditions unless local circumstances are not supportive. "]
["Historical Daily Peak Hour Factor"," ","The ratio of Peak Hour Peak Direction Passenger Demand for a typical route (i.e. representative of he system as a whole) to its total daily boardings in both directions. His factor helps to convert daily passenger flows into peak hour passenger flows. It should be ideally be determined by looking at historical data. Please note that this factor is usually higher for public transport as compared to total traffic.",null,"COMPETITIVE","Likely to be a good choice for the input conditions if specific local circumstances are supportive."]
["Local Transit",null,"Public transport operating on fixed routes with frequent stops (100-400 m apart), generally in mixed traffic on surface roadways, relying heavily on walk access and egress.",null,"MARGINAL","Possibly a good choice for the input conditions if specific local conditions are strongly supportive."]
["Local Transit Boardings",null,"The annual number of passengers boarding local  transit vehicles, counting separately each boarding made in the course of single journey or trip between origin and destination.  Also known as unlinked passenger trips (UPT). Boardings on regional services should not be included in city totals when using this tool.",null,"UNFAVORABLE","Not likely to be a good choice for the input conditions"]
["Local Transit Service Area",null,"The reasonably contiguous area served by the local transit network, not including regional services. Indicative extent would be the area within 1 km of regularly served local stops.  This area does not include portions of the metropolis connected to the local service area solely by regional services. ",null,"OVER CAPACITY","Demand under the input conditions is lilely to exceed capacity (as defined herein) under peak conditions."]
["Mean Local Transit Trip Length",null,"The average distance traveled by one public transit boarding passenger, calculated by dividing total local transit person-km by total local transit boardings."]
["Network Extent",null,"The number of kilometres of route in a public transport network, without double-counting kilometres where routes share the same path. "]
["Passenger Traffic Density","PTD","The total number annual transit passengers passing the average point along a system or route in both directions combined, formed by dividing system PKT by network extent (for a system) or route PKT by route length (for a single route). "]
["Passenger-Kilometers Travelled ","PKT","The total  distance  travelled by passengers on transit vehicles (for a single route or a system), which may be determined by multiplying the number of unlinked passenger trips by the average length of such trips."]
["Peak Hour Peak Direction Passenger Demand","PHPD","The number of transit passengers carried in the peak hour in the peak direction.  This occurs almost universally on weekdays, and is measured for a single route at its maxmum load point.  "," "]
["Projected Annual Rapid Transit Passenger Boardings in a Corridor/ Annual Corridor Ridership",null,"The estimated or projected annual passenger boardings for a specific rapid transit corridor of known length. The estimate should be consistent with operating characteristics (such as average speed) for the available ROW"]
["Rapid Transit","RT","Public transport operating on fixed routes at a significantly higher averge speed than local service, usually in exclusive rights-of-way and/or completely separated from surface traffic.  Access depends on both walking and local public transport service.  Stations are typically 800m-2km apart. "]
["Regional Transit",null,"Public transport operating on fixed routes within and outside the local service area, offering higher average speeds than even rapid transit, with average station spacings usually longer than 2 km.  A large share of access may be by motorized transport. "]
["Right-of-Way","ROW","Land that is used for moving vehicles carrying passengers or goods, such as railways or highways. Rights-of-way may be identified, purchased, or reserved in advance for future transportation use, and may be requirred to construct elevated or underground rapid transit. "]
["RoW Class",null,"Classification of the type of operating environment of the RoW. ROW Class A = fully grade-separated ROW, Class B = at-grade lane separation, Class C = mixed traffic. "]
["Total Annualized Cost","TAC","Total annualized cost is the annualized value of the total net present cost expressed in per PKT."]
["Vehicle Capacity",null,"The average number of people that a vehicle can be scheduled to carry at capacity  (as deined herein)"]

{"sheet":"Assumptions and Thresholds","index":4,"n_rows":30,"n_cols":14,"rows_kept":30,"cut":false,"hidden":false,"merged":[[13,12,13,13],[1,1,1,2],[13,7,13,8],[13,4,13,5],[13,1,13,2],[10,1,11,2]]}
[]
[null,"Standard Vehicle Types and Capacities"]
[null,"Vehicle Types","Vehicle Capacity (apprx)"]
[null,"Bus Standard (12 m)",65]
[null,"Bus Articulated (18 m)",116]
[null,"Bus Bi-Articulated (24 m)",172]
[null,"LRT single-articulated vehicle ( 25  m)",167]
[null,"LRT train of four single-articulated vehicles",657]
[null,"Metro/Rapid train (small = 2 x  17  m)",287]
[null,"Metro/Rapid Train (large = 8 x  25  m)",1637]
[null,"Capacities based vehicle dimensions per TCQSM methods, using 6 persons per m2 of standee space and load diversity factors depending on train lengt."]
[]
[]
["Rapid Transit Modes","Right-of-Way",null,"Maximum Vehicle Capacity","Frequencies (services/ direction/ hour)",null,"Passengers Peak Hour Per Direction","Population+Jobs / Sq.Km within Transit Influence Zone",null,"Reliability Factor","Potential to Create Barrier to Pedestrian Mobility","Impact on Livability (Noise and Infrastructural clutter)","Indicative Total Cost* per Passenger-Km Travelled (INITIAL ASSESSMENT)"]
[null,"Description","Class**","Maximum","Minimum","Maximum","Maximum","Minimum","Maximum",null,null,null,"Higher Case","Lower Case"]
["BRT Rapid","Physically separated busway or segregated bus lanes with continuous passing lane.  Max vehicle length 24m","A",{"$f":"C6","v":172},8,190,{"$f":"F16*D16","v":32680},10000,30000,"High","High","Moderate",{"$f":"'Demand and Cost Thresholds'!B25","v":0.31800809498012605},{"$f":"'Demand and Cost Thresholds'!C25","v":0.4301316391665001}]
["BRT Semi-Rapid 1","Dedicated at-grade lanes with passing lane at stations and 'spot' priority features.  Max vehicle length 24m","B",{"$f":"C6","v":172},6,94,{"$f":"F17*D17","v":16168},6000,20000,"Moderate","Low","Low",{"$f":"'Demand and Cost Thresholds'!B26","v":0.36159184695452085},{"$f":"'Demand and Cost Thresholds'!C26","v":0.43258717639424932}]
["BRT Semi-Rapid 2","Dedicated at-grade BRT lane with general traffic turns allowed at signals.  Max vehicle length 18m","B",{"$f":"C5","v":116},6,71,8236,5000,20000,"Moderate","Low","Low",{"$f":"'Demand and Cost Thresholds'!B26","v":0.36159184695452085},{"$f":"'Demand and Cost Thresholds'!C26","v":0.43258717639424932}]
["LRT Semi-Rapid","Dedicated tracks at grade.  Maximum train length 150m","B",{"$f":"C8","v":657},8,40,26280,10000,30000,"Moderate","Moderate","Low",{"$f":"'Demand and Cost Thresholds'!B27","v":0.36929124263725205},{"$f":"'Demand and Cost Thresholds'!C27","v":0.47759396443888535}]
["Metro/ Rail Rapid Transit","Elevated double track","A",{"$f":"C10","v":1637},10,60,98220,30000,60000,"High","High","High",{"$f":"'Demand and Cost Thresholds'!B28","v":0.33749318972769782},{"$f":"'Demand and Cost Thresholds'!C28","v":0.47873727416156253}]
[null,"** ROW Class A = fully grade-separated ROW, Class B = at-grade lane separation, Class C = mixed traffic"]
[null,"* Cost estimates are based on the Luigi, Allen, Bruun Technology Selection Model"]
[]
["Assumptions:","The following modes are excluded in this assessment:"]
[null,"·       Local Bus – because it serves a local connector and feeder connection only and cannot be classified as \"rapid\""]
[null,"·        Streetcar – because it operates in mixed traffic more often and cannot be classified as \"rapid\""]
[null,"·        Commuter Rail – because it serves the regional transit function, not urban 'rapid'"]
[null,"·        Monorail / Skytrain (suspension rail) / cable cars – because it does not adapt itself to forming a network, an essential requirement for urban transit, could be used as feeder lines in atypical topographies as deemed necessary."]
[null,"·        Personal Rapid Transit – because they are not a \"public\" transit system "]
[null,"The right-of-way costs for real estate is not considered in this tool"]

{"sheet":"Demand and Cost Thresholds","index":5,"n_rows":44,"n_cols":13,"rows_kept":44,"cut":false,"hidden":true,"merged":[]}
["INPUT"]
["Service Area (km2)",{"$f":"'INITIAL Assessment'!D9","v":3000}]
["Service Area Population",{"$f":"'INITIAL Assessment'!D10","v":23305971}]
["Local Public Transport Annual Passenger-km Traveled",{"$f":"'INITIAL Assessment'!D21","v":12355200000}]
["Corridor Length (km)",{"$f":"'DETAILED Evaluation'!D12","v":22}]
["Estimated Annual Passengers (Boardings)",{"$f":"'DETAILED Evaluation'!D13","v":12105000}]
[]
["Intermediate/Working Values","Higher Case","Lower Case "]
["INITIAL ASSESSMENT"]
["Population per square km of service area",{"$f":"B3/B2","v":7768.6570000000002},{"$f":"B3/B2","v":7768.6570000000002}]
["Post-rapid passenger-km per square km",{"$f":"1.8*B4/B2","v":7413120},{"$f":"1.4*B4/B2","v":5765760},null,null,null,null,null,null,null,null," "]
["Gross post-rapid passenger-km",{"$f":"$B$2*B11","v":22239360000},{"$f":"$B$2*C11","v":17297280000}]
["Notional network route km per square km",{"$f":"0.6*EXP(1.735-0.28*LN($B$2))*EXP(-11.131+0.559*LN(B10)+0.327*LN(B11))","v":0.13967544651501212},{"$f":"1.275*EXP(1.735-0.28*LN($B$2))*EXP(-11.131+0.559*LN(C10)+0.327*LN(C11))","v":0.27339386283842115},null," "]
["Notional network route kilometres",{"$f":"B13*$B$2","v":419.02633954503636},{"$f":"C13*$B$2","v":820.18158851526346}]
["Rapid transit share of gross PKT",{"$f":"1/(1+EXP(5.235-0.5-0.43197*LN(B11)+0.0926*LN(B10)))","v":0.78052585922457562},{"$f":"1/(1+EXP(5.235+0.55-0.43197*LN(C11)+0.0926*LN(C10)))","v":0.52751546383439007}," "]
["Rapid transit person-km",{"$f":"B15*B12","v":17358395572.60466},{"$f":"C15*C12","v":9124582682.2733192}]
["Indicative Passenger Traffic Density (INITIAL)",{"$f":"B16/B14","v":41425547.595532484},{"$f":"C16/C14","v":11125076.214879593}," "]
["DETAILED EVALUATION",null,null,null,null,null,"High","Low"]
["Average Trip Length (km)",{"$f":"$B$5*($G$19+$G$20*LN($B$5))","v":12.291271838354199},{"$f":"$B$5*($H$19+$H$20*LN($B$5))","v":5.8611279981072002},null,null,"Intercept",0.73219545797730379,0.44207630798869102]
["Indicative Passenger Traffic Density (DETAIL)",{"$f":"(B19/$B5)*$B6","v":6762992.9819671623},{"$f":"(C19/$B5)*$B6","v":3224952.4735039845},null,null,"ln(L)",-5.6130346355532892E-2,-5.6829177092979737E-2,null,null,null,null," "]
[]
["INITIAL COST ASSESSMENT"]
["PTD in millions",{"$f":"B17/1000000","v":41.425547595532485},{"$f":"C17/1000000","v":11.125076214879593},null," ","Coeff A","Coeff B","Coeff C"]
["Reference Cost per PKT",{"$f":"MIN(1,($F24+$G$24*B$23+$H24/B$23))","v":0.37637610709624736},{"$f":"MIN(1,$F24+$G$24*C$23+$H24/C$23)","v":0.44525573612045488},null,"Capacity",0.42170872177659363,-1.3438918928402337E-3,0.42829222821236312]
["BRT A Indicative Total Cost per PKT",{"$f":"($F25+$G$24*B$23+$H25/B$23)","v":0.31800809498012605},{"$f":"$F25+$G$24*C$23+$H25/C$23","v":0.4301316391665001},null,33.20288,0.34746333778842714,-9.1042842340321789E-4,1.0860210523897416,null,null,null,null," "]
["BRT B Indicative Total Cost per PKT",{"$f":"($F26+$G$24*B$23+$H26/B$23)","v":0.36159184695452085},{"$f":"$F26+$G$24*C$23+$H26/C$23","v":0.43258717639424932},null,16.426687999999999,0.40614766420241688,-3.2741497355107178E-4,0.46047148722241804,null,null,null,null," "]
["LRT B Indicative Total Cost per PKT",{"$f":"($F27+$G$24*B$23+$H27/B$23)","v":0.36929124263725205},{"$f":"$F27+$G$24*C$23+$H27/C$23","v":0.47759396443888535},null,26.700479999999999,0.40014933293593569,-2.0217551953398221E-4,1.027907326907624]
["Metro Indicative Total Cost per PKT",{"$f":"($F28+$G$24*B$23+$H28/B$23)","v":0.33749318972769782},{"$f":"$F28+$G$24*C$23+$H28/C$23","v":0.47873727416156253},null,99.791520000000006,0.35625657808918459,-4.3578086713951604E-4,1.5289369776607524]
[]
["DETAILED COST ASSESSMENT"]
["PTD in millions",{"$f":"B20/1000000","v":6.7629929819671624},{"$f":"C20/1000000","v":3.2249524735039845},null," ","Coeff A","Coeff B","Coeff C",null,"Lookup"]
["Reference Cost per PKT",{"$f":"MIN(1,$F32+$G$32*B$31+$H32/B$31)","v":0.47594879007891283},{"$f":"MIN(1,($F32+$G$32*C$31+$H32/C$31))","v":0.55018048313118562},null,"Capacity",0.42170872177659363,-1.3438918928402337E-3,0.42829222821236312,null,"Ratio","Rating"]
["Indicative Total Cost per PKT",null,null,null,null,null,null,null,null,0,3]
["BRT Rapid",{"$f":"MIN(1,$F34+$G$32*B$31+$H34/B$31)","v":0.49895751029152635},{"$f":"MIN(1,($F34+$G$32*C$31+$H34/C$31))","v":0.67988502695784403},null,{"$f":"32680*1016/1000000","v":33.20288},0.34746333778842714,-9.1042842340321789E-4,1.0860210523897416,null,1.05,2]
["BRT Semi-Rapid 1",{"$f":"MIN(1,$F35+$G$32*B$31+$H35/B$31)","v":0.46514587126014478},{"$f":"MIN(1,($F35+$G$32*C$31+$H35/C$31))","v":0.54459763741421852},null,{"$f":"16168*1016/1000000","v":16.426687999999999},0.40614766420241688,-3.2741497355107178E-4,0.46047148722241804,null,1.1499999999999999,1]
["BRT Semi-Rapid 2",{"$f":"MIN(1,$F36+$G$32*B$31+$H36/B$31)","v":0.46514587126014478},{"$f":"MIN(1,($F36+$G$32*C$31+$H36/C$31))","v":0.54459763741421852},null,{"$f":"16168*1016/1000000","v":16.426687999999999},0.40614766420241688,-3.2741497355107178E-4,0.46047148722241804,null,1.35,0]
["LRT Semi-Rapid",{"$f":"MIN(1,$F37+$G$32*B$31+$H37/B$31)","v":0.54305060498252522},{"$f":"MIN(1,($F37+$G$32*C$31+$H37/C$31))","v":0.71455099670666011},null,{"$f":"26280*1016/1000000","v":26.700479999999999},0.40014933293593569,-2.0217551953398221E-4,1.027907326907624,null,null,0]
["Metro/ Rail Rapid Transit",{"$f":"MIN(1,$F38+$G$32*B$31+$H38/B$31)","v":0.57324186176924374},{"$f":"MIN(1,($F38+$G$32*C$31+$H38/C$31))","v":0.82601856263038798},null,{"$f":"98220*1016/1000000","v":99.791520000000006},0.35625657808918459,-4.3578086713951604E-4,1.5289369776607524]
["Results - Total Cost Rating"]
["BRT Rapid",{"$f":"IF(B$31>$E34,$K$37,VLOOKUP(B34/B$32,$J$33:$K$36,2))","v":3},{"$f":"IF(C$31>$E34,$K$37,VLOOKUP(C34/C$32,$J$33:$K$36,2))","v":1}]
["BRT Semi-Rapid 1",{"$f":"IF(B$31>$E35,$K$37,VLOOKUP(B35/B$32,$J$33:$K$36,2))","v":3},{"$f":"IF(C$31>$E35,$K$37,VLOOKUP(C35/C$32,$J$33:$K$36,2))","v":3}]
["BRT Semi-Rapid 2",{"$f":"IF(B$31>$E36,$K$37,VLOOKUP(B36/B$32,$J$33:$K$36,2))","v":3},{"$f":"IF(C$31>$E35,$K$37,VLOOKUP(C35/C$32,$J$33:$K$36,2))","v":3}]
["LRT Semi-Rapid",{"$f":"IF(B$31>$E37,$K$37,VLOOKUP(B37/B$32,$J$33:$K$36,2))","v":2},{"$f":"IF(C$31>$E37,$K$37,VLOOKUP(C37/C$32,$J$33:$K$36,2))","v":1}]
["Metro/ Rail Rapid Transit",{"$f":"IF(B$31>$E38,$K$37,VLOOKUP(B38/B$32,$J$33:$K$36,2))","v":1},{"$f":"IF(C$31>$E38,$K$37,VLOOKUP(C38/C$32,$J$33:$K$36,2))","v":0}]

{"sheet":"Drop-Down Values","index":6,"n_rows":15,"n_cols":26,"rows_kept":15,"cut":false,"hidden":true,"merged":[[0,0,3,0],[0,4,2,4],[0,7,2,7],[0,13,1,13]]}
["Daily Transit Traffic to Peak Transit Traffic Factor","SELECT",null,null,"Score for Screening","SELECT",null,"ROW Dedication Class","SELECT",null,"COST LOOKUP",null,null,"Subjective-Questions","SELECT",null,"Mode","Local Tech Sum","Country Tech Sum","Is there an electrified regional rail in the metro area?","Is there a local electrified rail (streetcar or tram) in the metro area?","Are articulated buses operated in the local service in the metro area?","Do exclusive bus lanes exist in the metro area?","Is there metro elsewhere in the country","Is there BRT B elsewhere in the country","Is there BRT A elsewhere in the country"]
[null,0.02,null,null,null,2,null,null,"A",null,0,"FAVORABLE",null,null,"NO",null,"BRT Rapid",{"$f":"SUM(T2:W2)","v":0},{"$f":"SUM(X2:Z2)","v":1},0,0,{"$f":"IF('DETAILED Evaluation'!$D$20=\"YES\",1,0)","v":0},0,0,0,{"$f":"IF('DETAILED Evaluation'!$D$24=\"YES\",1,0)","v":1}]
[null,0.03,null,null,null,1,null,null,"B",null,1.05,"COMPETITIVE",null,null,"YES",null,"BRT Semi-Rapid 1",{"$f":"SUM(T3:W3)","v":2},{"$f":"SUM(X3:Z3)","v":2},0,0,1,{"$f":"IF('DETAILED Evaluation'!$D$21=\"YES\",1,0)","v":1},0,{"$f":"IF('DETAILED Evaluation'!$D$23=\"YES\",1,0)","v":1},{"$f":"IF('DETAILED Evaluation'!$D$24=\"YES\",1,0)","v":1}]
[null,0.04,null,null,null,0,null,null,"C",null,1.1499999999999999,"MARGINAL",null,null,null,null,"BRT Semi-Rapid 2",{"$f":"SUM(T4:W4)","v":1},{"$f":"SUM(X4:Z4)","v":2},0,0,{"$f":"IF('DETAILED Evaluation'!$D$20=\"YES\",1,0)","v":0},{"$f":"IF('DETAILED Evaluation'!$D$21=\"YES\",1,0)","v":1},0,{"$f":"IF('DETAILED Evaluation'!$D$23=\"YES\",1,0)","v":1},{"$f":"IF('DETAILED Evaluation'!$D$24=\"YES\",1,0)","v":1}]
[null,0.05,null,null,null,null,null,null,null,null,1.35,"UNFAVORABLE",null,null,null,null,"LRT Semi-Rapid",{"$f":"SUM(T5:W5)","v":1},{"$f":"SUM(X5:Z5)","v":0},{"$f":"IF('DETAILED Evaluation'!$D$18=\"YES\",1,0)","v":1},{"$f":"IF('DETAILED Evaluation'!$D$19=\"YES\",1,0)","v":0},0,0,0,0,0]
[null,0.06,null,null,null,null,null,null,null,null,null,"OVER CAPACITY",null,null,null,null,"Metro/ Rail Rapid Transit",{"$f":"SUM(T6:W6)","v":2},{"$f":"SUM(X6:Z6)","v":1},{"$f":"IF('DETAILED Evaluation'!$D$18=\"YES\",2,0)","v":2},0,0,0,1,0,0]
[null,7.0000000000000007E-2]
[null,0.08]
[null,0.09]
[null,0.1,null,null,null,null,null,null,null,null,"Ratio of Notional PHPD to Capacity","Rating "]
[null,0.11,null,null,null,null,null,null,null,null,0,"UNFAVORABLE","does not use investment adequately)"]
[null,0.12,null,null,null,null,null,null,null,null,0.1,"MARGINAL"]
[null,0.13,null,null,null,null,null,null,null,null,0.25,"FAVORABLE"]
[null,0.14000000000000001,null,null,null,null,null,null,null,null,0.85,"UNFAVORABLE"]
[null,0.15,null,null,null,null,null,null,null,null,1,"OVER CAPACITY"]